{"id":2762,"date":"2022-09-02T16:30:07","date_gmt":"2022-09-02T16:30:07","guid":{"rendered":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/my-account\/"},"modified":"2024-01-27T09:12:10","modified_gmt":"2024-01-27T09:12:10","slug":"my-account","status":"publish","type":"page","link":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2762","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/pages\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":0,"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/pages\/2762\/revisions"}],"wp:attachment":[{"href":"https:\/\/liberatingsolution.tech\/design-demo\/zen\/wp-json\/wp\/v2\/media?parent=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}